{"id":6289,"date":"2023-07-24T18:32:36","date_gmt":"2023-07-24T18:32:36","guid":{"rendered":"https:\/\/nordicmarkets.com\/client-support-centre\/register\/"},"modified":"2023-07-24T18:32:36","modified_gmt":"2023-07-24T18:32:36","slug":"register","status":"publish","type":"page","link":"https:\/\/nordicmarkets.com\/client-support-centre\/register\/","title":{"rendered":"Register"},"content":{"rendered":"\n<form id=\"pms_register-form\" class=\"pms-form \" method=\"POST\">\n\n    \n    <input type=\"hidden\" id=\"pmstkn\" name=\"pmstkn\" value=\"37f3f7fbdd\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/client-support-centre\/wp-json\/wp\/v2\/pages\/6289\" \/>\n    <ul class=\"pms-form-fields-wrapper\">\n\n        \n        \n        <div class=\"pms-account-section-wrapper\">\n            \n                        <li class=\"pms-field pms-user-login-field \">\n                <label for=\"pms_user_login\">Username *<\/label>\n                <input id=\"pms_user_login\" name=\"user_login\" type=\"text\" value=\"\" \/>\n\n                            <\/li>\n\n                        <li class=\"pms-field pms-user-email-field \">\n                <label for=\"pms_user_email\">E-mail *<\/label>\n                <input id=\"pms_user_email\" name=\"user_email\" type=\"text\" value=\"\" \/>\n\n                            <\/li>\n\n                        <li class=\"pms-field pms-first-name-field \">\n                <label for=\"pms_first_name\">First Name<\/label>\n                <input id=\"pms_first_name\" name=\"first_name\" type=\"text\" value=\"\" \/>\n\n                            <\/li>\n\n                        <li class=\"pms-field pms-last-name-field \">\n                <label for=\"pms_last_name\">Last Name<\/label>\n                <input id=\"pms_last_name\" name=\"last_name\" type=\"text\" value=\"\" \/>\n\n                            <\/li>\n\n                        <li class=\"pms-field pms-pass1-field \">\n                <label for=\"pms_pass1\">Password *<\/label>\n                <input id=\"pms_pass1\" name=\"pass1\" type=\"password\" \/>\n\n                \n                            <\/li>\n\n                        <li class=\"pms-field pms-pass2-field \">\n                <label for=\"pms_pass2\">Repeat Password *<\/label>\n                <input id=\"pms_pass2\" name=\"pass2\" type=\"password\" \/>\n\n                            <\/li>\n\n                    <\/div>\n\n        \n        <li class=\"pms-field pms-field-subscriptions \"><input type=\"hidden\" id=\"pmstkn2\" name=\"pmstkn2\" value=\"6f9274d82e\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/client-support-centre\/wp-json\/wp\/v2\/pages\/6289\" \/><\/li>\n    <\/ul>\n\n    <span id=\"pms-submit-button-loading-placeholder-text\" style=\"display: none;\">Processing. Please wait...<\/span>\n            <input class=\"pms-form-submit\" name=\"pms_register\" type=\"submit\" value=\"Register\" \/>\n    \n<\/form>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"class_list":["post-6289","page","type-page","status-publish","hentry","no-post-thumbnail"],"acf":[],"_links":{"self":[{"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/pages\/6289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/comments?post=6289"}],"version-history":[{"count":0,"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/pages\/6289\/revisions"}],"wp:attachment":[{"href":"https:\/\/nordicmarkets.com\/client-support-centre\/wp-json\/wp\/v2\/media?parent=6289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}